{"id":1192,"date":"2018-03-28T05:55:04","date_gmt":"2018-03-28T05:55:04","guid":{"rendered":"http:\/\/www.vispertheater.ch\/wordpress\/?p=1192"},"modified":"2018-03-28T05:55:04","modified_gmt":"2018-03-28T05:55:04","slug":"rettet-rumpelstilzchen-grosser-wettbewerb","status":"publish","type":"post","link":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/","title":{"rendered":"Rettet Rumpelstilzchen &#8211; grosser Wettbewerb"},"content":{"rendered":"<p><a href=\"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-1190\" src=\"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3-632x892.jpg\" alt=\"Rumpelstilzchen_Plakat_A3.indd\" width=\"632\" height=\"892\" srcset=\"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3-632x892.jpg 632w, https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3-1020x1439.jpg 1020w, https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3-35x50.jpg 35w, https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3-650x917.jpg 650w, https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3-1000x1411.jpg 1000w\" sizes=\"(max-width: 632px) 100vw, 632px\" \/><\/a><\/p>\n<p>Du hast Spass am Malen und bist zwischen 3 und 12 Jahre alt?<\/p>\n<p>Dann nimm am M\u00e4rchenmalwettbewerb f\u00fcr alle Kinder teil!\u00a0 Du kannst Eintritte f\u00fcr unser Theater gewinnen.<\/p>\n<p>Lasse deiner Fantasie freien Lauf: Male dein M\u00e4rchenbild\u00a0ganz so, wie es\u00a0dir gef\u00e4llt. Vergiss nicht deinen Namen, dein Alter und deine Adresse auf die R\u00fcckseite der Zeichnung zu schreiben. Wir freuen uns auf deine Ideen!<\/p>\n<p>Alles, was du noch wissen musst:<\/p>\n<p>Teilnehmen d\u00fcrfen alle zwischen 3 und 12 Jahren.<\/p>\n<p>Die Tickets verlosen wir f\u00fcr diese drei Altersgruppen: 3 bis 5 Jahre, 6 bis 7 Jahre und 8 bis 12 Jahre.<\/p>\n<p>Mitmachen kannst du bis am 15.05.2018<\/p>\n<p>Schicke deine Zeichnung an:<\/p>\n<p>Visper Theater<\/p>\n<p>\u201eMuggini\u201c<br \/>\nPostfach 590<br \/>\n3930 Visp<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du hast Spass am Malen und bist zwischen 3 und 12 Jahre alt? Dann nimm am M\u00e4rchenmalwettbewerb f\u00fcr alle Kinder teil!\u00a0 Du kannst Eintritte f\u00fcr unser Theater gewinnen. Lasse deiner [&hellip;]<\/p>\n<p><a href=\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/\" class=\"more-link style1-button\">Weiterlesen<\/a><\/p>","protected":false},"author":1,"featured_media":1190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rettet Rumpelstilzchen - grosser Wettbewerb - Visper Theater<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rettet Rumpelstilzchen - grosser Wettbewerb - Visper Theater\" \/>\n<meta property=\"og:description\" content=\"Du hast Spass am Malen und bist zwischen 3 und 12 Jahre alt? Dann nimm am M\u00e4rchenmalwettbewerb f\u00fcr alle Kinder teil!\u00a0 Du kannst Eintritte f\u00fcr unser Theater gewinnen. Lasse deiner [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/\" \/>\n<meta property=\"og:site_name\" content=\"Visper Theater\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/79472610286\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-28T05:55:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3539\" \/>\n\t<meta property=\"og:image:height\" content=\"4993\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/#website\",\"url\":\"https:\/\/www.vispertheater.ch\/wordpress\/\",\"name\":\"Visper Theater\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vispertheater.ch\/wordpress\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#primaryimage\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3.jpg\",\"contentUrl\":\"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3.jpg\",\"width\":3539,\"height\":4993},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#webpage\",\"url\":\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/\",\"name\":\"Rettet Rumpelstilzchen - grosser Wettbewerb - Visper Theater\",\"isPartOf\":{\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#primaryimage\"},\"datePublished\":\"2018-03-28T05:55:04+00:00\",\"dateModified\":\"2018-03-28T05:55:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/#\/schema\/person\/eda652cd46d93ef1b5519b8485a92703\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vispertheater.ch\/wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rettet Rumpelstilzchen &#8211; grosser Wettbewerb\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vispertheater.ch\/wordpress\/#\/schema\/person\/eda652cd46d93ef1b5519b8485a92703\",\"name\":\"admin\",\"url\":\"https:\/\/www.vispertheater.ch\/wordpress\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rettet Rumpelstilzchen - grosser Wettbewerb - Visper Theater","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/","og_locale":"de_DE","og_type":"article","og_title":"Rettet Rumpelstilzchen - grosser Wettbewerb - Visper Theater","og_description":"Du hast Spass am Malen und bist zwischen 3 und 12 Jahre alt? Dann nimm am M\u00e4rchenmalwettbewerb f\u00fcr alle Kinder teil!\u00a0 Du kannst Eintritte f\u00fcr unser Theater gewinnen. Lasse deiner [&hellip;]","og_url":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/","og_site_name":"Visper Theater","article_publisher":"https:\/\/www.facebook.com\/groups\/79472610286\/","article_published_time":"2018-03-28T05:55:04+00:00","og_image":[{"width":3539,"height":4993,"url":"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.vispertheater.ch\/wordpress\/#website","url":"https:\/\/www.vispertheater.ch\/wordpress\/","name":"Visper Theater","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vispertheater.ch\/wordpress\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"ImageObject","@id":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#primaryimage","inLanguage":"de-DE","url":"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3.jpg","contentUrl":"https:\/\/www.vispertheater.ch\/wordpress\/wp-content\/uploads\/2018\/03\/Rumpelstilzchen_Plakat_A3.jpg","width":3539,"height":4993},{"@type":"WebPage","@id":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#webpage","url":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/","name":"Rettet Rumpelstilzchen - grosser Wettbewerb - Visper Theater","isPartOf":{"@id":"https:\/\/www.vispertheater.ch\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#primaryimage"},"datePublished":"2018-03-28T05:55:04+00:00","dateModified":"2018-03-28T05:55:04+00:00","author":{"@id":"https:\/\/www.vispertheater.ch\/wordpress\/#\/schema\/person\/eda652cd46d93ef1b5519b8485a92703"},"breadcrumb":{"@id":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vispertheater.ch\/wordpress\/rettet-rumpelstilzchen-grosser-wettbewerb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vispertheater.ch\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Rettet Rumpelstilzchen &#8211; grosser Wettbewerb"}]},{"@type":"Person","@id":"https:\/\/www.vispertheater.ch\/wordpress\/#\/schema\/person\/eda652cd46d93ef1b5519b8485a92703","name":"admin","url":"https:\/\/www.vispertheater.ch\/wordpress\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/posts\/1192"}],"collection":[{"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=1192"}],"version-history":[{"count":2,"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/posts\/1192\/revisions"}],"predecessor-version":[{"id":1194,"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/posts\/1192\/revisions\/1194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/media\/1190"}],"wp:attachment":[{"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=1192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=1192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vispertheater.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=1192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}